{"id":18291,"date":"2025-08-03T17:56:58","date_gmt":"2025-08-03T15:56:58","guid":{"rendered":"https:\/\/www.colindres.es\/?post_type=project&#038;p=18291"},"modified":"2025-08-03T17:58:24","modified_gmt":"2025-08-03T15:58:24","slug":"colindres-celebra-su-tradicional-fiesta-de-san-roque-2","status":"publish","type":"project","link":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/","title":{"rendered":"COLINDRES CELEBRA SU TRADICIONAL FIESTA DE SAN ROQUE"},"content":{"rendered":"<p><em>Las actividades culturades, deportivas y festivas llenan la programaci\u00f3n del mes de agosto <\/em><\/p>\n<p>El Ayuntamiento de Colindres ha preparado un nutrido programa de actividades de car\u00e1cter festivo, l\u00fadico, deportivo y cultural para las primeras semanas del mes de agosto en el que destaca la Festividad de San Roque el d\u00eda 16.<\/p>\n<p>A las seis de la tarde tendr\u00e1 lugar la misa en la ermita en honor al Santo, a la que le seguir\u00e1 la procesi\u00f3n para despu\u00e9s disfrutar de la tradicional sardinada de la que se encargar\u00e1n las pe\u00f1as locales.<\/p>\n<p>Para que todos los vecinos y vecinas, as\u00ed como visitantes, puedan disfrutar de la jornada, habr\u00e1 tren de calle desde las cuatro de la tarde hasta las nueve de la noche.<\/p>\n<p>El fin de semana de San Roque se completa con la celebraci\u00f3n, el domingo d\u00eda 17, de la XXXI Bandera R\u00edo As\u00f3n de Traineras. Una prueba de la liga ARC2 que se desarrollar\u00e1 en el puerto. Por la noche se podr\u00e1 disfrutar de la XXXVII Muestra Internacional de Folklore \u201cPor Tierras de Cantabria\u201d, en este caso, con un conjunto llegado desde Ucrania.<\/p>\n<p>Una semana antes, el domingo 10, tambi\u00e9n habr\u00e1 actuaci\u00f3n de Folklore en los jardines de la Casa de Cultura: \u201cTaka Iki\u201d, de las Islas Marquesas.<\/p>\n<p>Esta misma tarde, a las 20.00 horas, concierto de Soneto 21 en los jardines de la casa de Cultura.<\/p>\n<p><strong>OTRAS ACTIVIDADES<\/strong><\/p>\n<p>El s\u00e1bado, 9 de agosto, se ha organizado la segunda edici\u00f3n del festival Europa Pisando la Calle, un festival de cultura urbana que se desarrollar\u00e1 durante todo el d\u00eda. Una propuesta enfocada a los j\u00f3venes en la que el baloncesto, la m\u00fasica y la pintura ser\u00e1n los protagonistas en el entorno de la Plaza de la Esperanza y la Plaza de la Constituci\u00f3n; y un d\u00eda antes, el viernes 8, los j\u00f3venes que lo deseen har\u00e1n un descenso en canoa.<\/p>\n<p>La programaci\u00f3n contempla otras actividades para el p\u00fablico infantil como el Cine de Verano la noche del lunes, d\u00eda 18, con la proyecci\u00f3n de la pel\u00edcula Amigos Imaginarios a las 22.00 horas en los jardines de la casa de Cultura.<\/p>\n<p>Tambi\u00e9n, ese mismo d\u00eda, se presentar\u00e1 el libro \u201cMitolog\u00eda C\u00e1ntabra seg\u00fan Astronauta y Gato\u201d de Pilar Garc\u00eda Pantale\u00f3n. Ser\u00e1 a las 18.30 y servir\u00e1 para abrir la exposici\u00f3n, en la casa de cultura, de l\u00e1minas de dibujos que se podr\u00e1 contemplar hasta el d\u00eda 22.<\/p>\n<p>El jueves, d\u00eda 7, a partir de las 16.00 horas, se disputar\u00e1 la final de XXXII Memorial Jes\u00fas Ochoa de Bolo Palma en categor\u00eda juvenil y el viernes, d\u00eda 8, la final de primera categor\u00eda.<\/p>\n<p>El s\u00e1bado 9, a partir de las 20.30 horas, en el auditorio de la Casa de Cultura, podremos disfrutar del concierto \u201cUno sogno \u00e9 la speranza\u201d del d\u00fao Baalbeck, a cargo de la pianista Marie Vida Obeid y la soprano Laura Colina. Todo ello, sin olvidar que contin\u00faan \u201cLos Jueves del kiosco\u201d: m\u00fasica para bailar a cargo de Rosana Gar\u00edn en la Alameda del Kiosco del Ayuntamiento de 19.00 a 21.00 horas.<\/p>\n<p>Adem\u00e1s, del 7 al 10 se celebra la liga Agility en las pistas de Atletismo a las 10 de la ma\u00f1ana a excepci\u00f3n del domingo d\u00eda 10, que la competici\u00f3n comenzar\u00e1 alas 9 de la ma\u00f1ana.<\/p>\n<p>Por otra parte, del 8 al 17 de agosto, a las 20.00 horas, quienes lo deseen podr\u00e1n disfrutar de un espect\u00e1culo de circo a cargo de Stellar Circus, instalado en la Avenida Europa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las actividades culturades, deportivas y festivas llenan la programaci\u00f3n del mes de agosto El Ayuntamiento de Colindres ha preparado un nutrido programa de actividades de car\u00e1cter festivo, l\u00fadico, deportivo y cultural para las primeras semanas del mes de agosto en el que destaca la Festividad de San Roque el d\u00eda 16. A las seis de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18292,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"project_category":[6],"project_tag":[],"class_list":["post-18291","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COLINDRES CELEBRA SU TRADICIONAL FIESTA DE SAN ROQUE - Ayuntamiento de Colindres<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COLINDRES CELEBRA SU TRADICIONAL FIESTA DE SAN ROQUE - Ayuntamiento de Colindres\" \/>\n<meta property=\"og:description\" content=\"Las actividades culturades, deportivas y festivas llenan la programaci\u00f3n del mes de agosto El Ayuntamiento de Colindres ha preparado un nutrido programa de actividades de car\u00e1cter festivo, l\u00fadico, deportivo y cultural para las primeras semanas del mes de agosto en el que destaca la Festividad de San Roque el d\u00eda 16. A las seis de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ayuntamiento de Colindres\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-03T15:58:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.colindres.es\/wp-content\/uploads\/2025\/08\/PHOTO-2025-08-01-20-59-16.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"934\" \/>\n\t<meta property=\"og:image:height\" content=\"1315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/\",\"url\":\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/\",\"name\":\"COLINDRES CELEBRA SU TRADICIONAL FIESTA DE SAN ROQUE - Ayuntamiento de Colindres\",\"isPartOf\":{\"@id\":\"https:\/\/www.colindres.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.colindres.es\/wp-content\/uploads\/2025\/08\/PHOTO-2025-08-01-20-59-16.jpg\",\"datePublished\":\"2025-08-03T15:56:58+00:00\",\"dateModified\":\"2025-08-03T15:58:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#primaryimage\",\"url\":\"https:\/\/www.colindres.es\/wp-content\/uploads\/2025\/08\/PHOTO-2025-08-01-20-59-16.jpg\",\"contentUrl\":\"https:\/\/www.colindres.es\/wp-content\/uploads\/2025\/08\/PHOTO-2025-08-01-20-59-16.jpg\",\"width\":934,\"height\":1315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.colindres.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"https:\/\/www.colindres.es\/index.php\/project\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"COLINDRES CELEBRA SU TRADICIONAL FIESTA DE SAN ROQUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.colindres.es\/#website\",\"url\":\"https:\/\/www.colindres.es\/\",\"name\":\"Ayuntamiento de Colindres\",\"description\":\"Dise\u00f1ado por NTIC&#039;s\",\"publisher\":{\"@id\":\"https:\/\/www.colindres.es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.colindres.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.colindres.es\/#organization\",\"name\":\"AYUNTAMIENTO DE COLINDRES\",\"url\":\"https:\/\/www.colindres.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.colindres.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.colindres.es\/wp-content\/uploads\/2017\/01\/LOGO-PRINCIPAL.jpg\",\"contentUrl\":\"https:\/\/www.colindres.es\/wp-content\/uploads\/2017\/01\/LOGO-PRINCIPAL.jpg\",\"width\":1209,\"height\":579,\"caption\":\"AYUNTAMIENTO DE COLINDRES\"},\"image\":{\"@id\":\"https:\/\/www.colindres.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COLINDRES CELEBRA SU TRADICIONAL FIESTA DE SAN ROQUE - Ayuntamiento de Colindres","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/","og_locale":"es_ES","og_type":"article","og_title":"COLINDRES CELEBRA SU TRADICIONAL FIESTA DE SAN ROQUE - Ayuntamiento de Colindres","og_description":"Las actividades culturades, deportivas y festivas llenan la programaci\u00f3n del mes de agosto El Ayuntamiento de Colindres ha preparado un nutrido programa de actividades de car\u00e1cter festivo, l\u00fadico, deportivo y cultural para las primeras semanas del mes de agosto en el que destaca la Festividad de San Roque el d\u00eda 16. A las seis de [&hellip;]","og_url":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/","og_site_name":"Ayuntamiento de Colindres","article_modified_time":"2025-08-03T15:58:24+00:00","og_image":[{"width":934,"height":1315,"url":"https:\/\/www.colindres.es\/wp-content\/uploads\/2025\/08\/PHOTO-2025-08-01-20-59-16.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/","url":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/","name":"COLINDRES CELEBRA SU TRADICIONAL FIESTA DE SAN ROQUE - Ayuntamiento de Colindres","isPartOf":{"@id":"https:\/\/www.colindres.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#primaryimage"},"image":{"@id":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.colindres.es\/wp-content\/uploads\/2025\/08\/PHOTO-2025-08-01-20-59-16.jpg","datePublished":"2025-08-03T15:56:58+00:00","dateModified":"2025-08-03T15:58:24+00:00","breadcrumb":{"@id":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#primaryimage","url":"https:\/\/www.colindres.es\/wp-content\/uploads\/2025\/08\/PHOTO-2025-08-01-20-59-16.jpg","contentUrl":"https:\/\/www.colindres.es\/wp-content\/uploads\/2025\/08\/PHOTO-2025-08-01-20-59-16.jpg","width":934,"height":1315},{"@type":"BreadcrumbList","@id":"https:\/\/www.colindres.es\/index.php\/project\/colindres-celebra-su-tradicional-fiesta-de-san-roque-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.colindres.es\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"https:\/\/www.colindres.es\/index.php\/project\/"},{"@type":"ListItem","position":3,"name":"COLINDRES CELEBRA SU TRADICIONAL FIESTA DE SAN ROQUE"}]},{"@type":"WebSite","@id":"https:\/\/www.colindres.es\/#website","url":"https:\/\/www.colindres.es\/","name":"Ayuntamiento de Colindres","description":"Dise\u00f1ado por NTIC&#039;s","publisher":{"@id":"https:\/\/www.colindres.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.colindres.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.colindres.es\/#organization","name":"AYUNTAMIENTO DE COLINDRES","url":"https:\/\/www.colindres.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.colindres.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.colindres.es\/wp-content\/uploads\/2017\/01\/LOGO-PRINCIPAL.jpg","contentUrl":"https:\/\/www.colindres.es\/wp-content\/uploads\/2017\/01\/LOGO-PRINCIPAL.jpg","width":1209,"height":579,"caption":"AYUNTAMIENTO DE COLINDRES"},"image":{"@id":"https:\/\/www.colindres.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/project\/18291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/types\/project"}],"author":[{"embeddable":true,"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/comments?post=18291"}],"version-history":[{"count":1,"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/project\/18291\/revisions"}],"predecessor-version":[{"id":18293,"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/project\/18291\/revisions\/18293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/media\/18292"}],"wp:attachment":[{"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/media?parent=18291"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/project_category?post=18291"},{"taxonomy":"project_tag","embeddable":true,"href":"https:\/\/www.colindres.es\/index.php\/wp-json\/wp\/v2\/project_tag?post=18291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}